{"id":169568,"date":"2025-06-16T16:36:24","date_gmt":"2025-06-16T20:36:24","guid":{"rendered":"https:\/\/clareprogramme.org\/?post_type=update&#038;p=169568"},"modified":"2025-08-01T09:24:48","modified_gmt":"2025-08-01T13:24:48","slug":"ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair","status":"publish","type":"update","link":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/","title":{"rendered":"L&rsquo;adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), <\/em> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l&rsquo;environnement, l&rsquo;\u00e9conomie et l&rsquo;aide humanitaire. Un <a href=\"https:\/\/www.oecd.org\/en\/publications\/the-toll-of-droughts_2f7891b9-en.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9tude r\u00e9cente de l&rsquo;OCDE<\/a> a r\u00e9v\u00e9l\u00e9 que l&rsquo;\u00e9pisode de s\u00e9cheresse moyen en 2025 sera au moins deux fois plus co\u00fbteux qu&rsquo;en 2000. Cette m\u00eame \u00e9tude a \u00e9galement mis en \u00e9vidence les cons\u00e9quences sociales des s\u00e9cheresses, qui influencent les sch\u00e9mas de migration et peuvent contribuer aux conflits en Afrique subsaharienne.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, plus de la moiti\u00e9 de la population mondiale est expos\u00e9e \u00e0 la s\u00e9cheresse (<a href=\"https:\/\/data.unccd.int\/people-exposed-to-drought\" target=\"_blank\" rel=\"noreferrer noopener\">UNCCD, 2025<\/a>). Le changement climatique rendant les ph\u00e9nom\u00e8nes climatiques extr\u00eames plus intenses et plus fr\u00e9quents, le renforcement de la r\u00e9sistance \u00e0 la s\u00e9cheresse doit \u00eatre une priorit\u00e9 mondiale urgente (<a href=\"https:\/\/www.ipcc.ch\/report\/ar6\/syr\/\" target=\"_blank\" rel=\"noreferrer noopener\">GIEC, 2023<\/a>). \u00c0 la fin de cette ann\u00e9e, les pays se r\u00e9uniront \u00e0 Panama pour examiner les pr\u00e9paratifs du tout premier rapport mondial sur les progr\u00e8s accomplis dans le renforcement de la r\u00e9silience aux s\u00e9cheresses (\u00e0 l&rsquo;\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l&rsquo;environnement, l&rsquo;\u00e9conomie et la situation humanitaire. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 17 juin marque <a href=\"https:\/\/www.un.org\/en\/observances\/desertification-day\" target=\"_blank\" rel=\"noreferrer noopener\">la Journ\u00e9e mondiale de lutte contre la d\u00e9sertification et la s\u00e9cheresse<\/a> \u2013 une occasion de reconna\u00eetre les investissements importants que les communaut\u00e9s font pour s&rsquo;adapter \u00e0 des risques de s\u00e9cheresse croissants. Dans l&rsquo;ensemble du portefeuille de recherche CLARE, des travaux sont en cours pour co-cr\u00e9er des solutions qui permettent la r\u00e9silience \u00e0 la s\u00e9cheresse et r\u00e9pondent aux besoins des personnes les plus vuln\u00e9rables du monde.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"the-effects-of-drought-in-clare-countries\"><strong>Les effets de la s\u00e9cheresse dans les pays CLARE<\/strong> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La s\u00e9cheresse \u00e9tait \u00e0 l&rsquo;ordre du jour de CLARExchange 2025, la premi\u00e8re r\u00e9union en personne de la communaut\u00e9 mondiale CLARE, qui a \u00e9t\u00e9 organis\u00e9e par FCDO et le CRDI en collaboration avec l&rsquo;Universit\u00e9 de Zambie. Lors de CLARExchange, les participants ont entendu l&rsquo;honorable ministre de l&rsquo;\u00e9conomie verte et de l&rsquo;environnement, M. Mike Elton Mposha, s&rsquo;exprimant au nom de Son Excellence le Pr\u00e9sident de la R\u00e9publique de Zambie, M. Hakainde Hichilema. M. Mposha a soulign\u00e9 les effets d\u00e9vastateurs de la s\u00e9cheresse de 2023\/2024, qui a affect\u00e9 l&rsquo;approvisionnement en \u00e9lectricit\u00e9 ainsi que la production alimentaire et d&rsquo;autres activit\u00e9s \u00e9conomiques en Zambie et dans l&rsquo;ensemble de la r\u00e9gion de l&rsquo;Afrique australe (<a href=\"https:\/\/afrp.undrr.org\/publication\/zambia-official-statement\" target=\"_blank\" rel=\"noreferrer noopener\">UNDRR, 2024;<\/a> <a href=\"https:\/\/www.worldweatherattribution.org\/human-induced-climate-change-increased-drought-severity-in-southern-horn-of-africa\/\" target=\"_blank\" rel=\"noreferrer noopener\">World Weather Attribution, 2023<\/a>; <a href=\"https:\/\/earthobservatory.nasa.gov\/images\/152711\/severe-drought-in-southern-africa\" target=\"_blank\" rel=\"noreferrer noopener\">NASA Earth Observatory, 2024<\/a>).&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab En tant que Zambiens, nous avons \u00e9t\u00e9 t\u00e9moins des effets d\u00e9vastateurs des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames &#8211; des inondations qui emportent nos maisons, nos \u00e9coles, nos cliniques et nos moyens de subsistance, aux s\u00e9cheresses qui laissent nos champs st\u00e9riles, en passant par les pr\u00e9cipitations irr\u00e9guli\u00e8res qui perturbent nos cycles agricoles et r\u00e9duisent \u00e0 n\u00e9ant la capacit\u00e9 de production d&rsquo;hydro\u00e9lectricit\u00e9 renouvelable de nos barrages qui s&rsquo;ass\u00e8chent en raison de s\u00e9cheresses record. \u00bb &#8211; M. Mike Elton Mposha, ministre de l&rsquo;\u00e9conomie verte et de l&rsquo;environnement, au nom de Son Excellence le pr\u00e9sident de la R\u00e9publique de Zambie, M. Hakainde Hichilema.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame, d&rsquo;autres pays b\u00e9n\u00e9ficiant de projets CLARE ont r\u00e9cemment connu des s\u00e9cheresses extr\u00eames, comme les pays de la Corne de l&rsquo;Afrique et l&rsquo;Inde (<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S2212094725000039?via%3Dihub\" target=\"_blank\" rel=\"noreferrer noopener\">Kimutai et al., 2025<\/a>; <a href=\"https:\/\/economictimes.indiatimes.com\/news\/india\/worst-drought-in-four-decades-says-d-k-shivakumar-on-karnatakas-water-crisis\/articleshow\/108386756.cms?from=mdr\" target=\"_blank\" rel=\"noreferrer noopener\">The Economic Times, 2024<\/a>). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"climate-resilient-development-in-the-context-of-extreme-drought\"><strong>D\u00e9veloppement r\u00e9sistant au climat dans le contexte d&rsquo;une s\u00e9cheresse extr\u00eame<\/strong> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Face \u00e0 ces preuves de plus en plus nombreuses, le pr\u00e9sident de la CdP30, Andr\u00e9 Corr\u00eaa do Lago, a observ\u00e9 que le d\u00e9bat sur le climat s&rsquo;est orient\u00e9 vers une nouvelle forme de d\u00e9ni &#8211; il ne s&rsquo;agit plus de rejeter le changement climatique lui-m\u00eame, dont il est d\u00e9sormais largement admis qu&rsquo;il se produit, mais plut\u00f4t de nier l&rsquo;id\u00e9e que les \u00e9conomies peuvent \u00eatre r\u00e9organis\u00e9es pour prosp\u00e9rer et se d\u00e9velopper gr\u00e2ce \u00e0 l&rsquo;utilisation proactive de la pr\u00e9voyance, de l&rsquo;adaptation et de la coop\u00e9ration, plut\u00f4t que de la gestion de la crise. (<a href=\"https:\/\/www.theguardian.com\/environment\/2025\/may\/28\/andre-correa-do-lago-cop30-interview-climate-crisis\" target=\"_blank\" rel=\"noreferrer noopener\">The Guardian, 2025<\/a>). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette nouvelle forme de \u00ab d\u00e9ni de l&rsquo;adaptation \u00bb signifie qu&rsquo;il est plus urgent que jamais de disposer de preuves positives des r\u00e9sultats positifs de l&rsquo;adaptation en mati\u00e8re de d\u00e9veloppement r\u00e9silient au climat. \u00c0 la suite d&rsquo;investissements consid\u00e9rables dans l&rsquo;adaptation par les communaut\u00e9s et les individus au niveau local, certaines de ces preuves peuvent \u00e9merger.  <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"climate-resilient-development-and-drought-the-case-of-kenya\"><strong>D\u00e9veloppement r\u00e9silient au climat et s\u00e9cheresse : le cas du Kenya<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Selon la <a href=\"https:\/\/unfccc.int\/sites\/default\/files\/2025-05\/KENYAS%20SECOND%20NATIONALLY%20DETERMINED%20CONTRIBUTION%202031_2035.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">deuxi\u00e8me contribution d\u00e9termin\u00e9e au niveau national du Kenya (2031-(2031-2035)<\/a>, les pertes subies entre 2020 et 2023 en raison de la s\u00e9cheresse la plus grave sur le plan m\u00e9t\u00e9orologique depuis 40 ans sont nettement inf\u00e9rieures \u00e0 celles subies en raison d&rsquo;une s\u00e9cheresse moins grave sur le plan m\u00e9t\u00e9orologique qui s&rsquo;est produite entre 2009 et 2011. Les deux ont \u00e9t\u00e9 co\u00fbteuses : la s\u00e9cheresse qui s&rsquo;est termin\u00e9e en 2023 a entra\u00een\u00e9 des pertes \u00e9conomiques sup\u00e9rieures \u00e0 650 millions USD et a r\u00e9duit le taux de croissance du PIB de 5,8 % en 2021 \u00e0 4,9 % en 2022. Cette perte est importante, mais elle est nettement moins \u00e9lev\u00e9e qu&rsquo;en 2011, lorsque la s\u00e9cheresse moins s\u00e9v\u00e8re avait caus\u00e9 plus de 11 milliards d&rsquo;USD de dommages et ralenti le PIB de 2,8 points de pourcentage par an en moyenne (<a href=\"https:\/\/www.gfdrr.org\/en\/kenya-post-disaster-needs-assessment\" target=\"_blank\" rel=\"noreferrer noopener\">GFDRR, 2017<\/a>).   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situation \u00e9tant complexe et de nombreux facteurs entrant en ligne de compte, il est n\u00e9cessaire de comparer des s\u00e9ries chronologiques de donn\u00e9es et d&rsquo;\u00e9l\u00e9ments suppl\u00e9mentaires figurant dans les <a href=\"https:\/\/knowledgeweb.ndma.go.ke\/Public\/Resources\/ResourceDetails.aspx?doc=91131a34-d495-4627-951f-196ba641ded8\" target=\"_blank\" rel=\"noreferrer noopener\">bulletins d&rsquo;alerte pr\u00e9coce publi\u00e9s par l&rsquo;Autorit\u00e9 nationale de gestion de la s\u00e9cheresse du Kenya,<\/a> qui documentent les changements survenus sur le terrain au cours des deux derni\u00e8res d\u00e9cennies. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es et les preuves disponibles soulignent la n\u00e9cessit\u00e9 d&rsquo;effectuer des recherches et des analyses pour d\u00e9terminer s&rsquo;il y a eu une r\u00e9elle \u00e9volution vers un d\u00e9veloppement r\u00e9silient au climat au Kenya &#8211; et, le cas \u00e9ch\u00e9ant, quels investissements r\u00e9alis\u00e9s par quels acteurs ont fait la diff\u00e9rence. Lors de la s\u00e9cheresse de 2018, des chercheurs ont affirm\u00e9 que la majorit\u00e9 des investissements dans le renforcement de la r\u00e9silience avaient \u00e9t\u00e9 r\u00e9alis\u00e9s par des associations locales d&rsquo;utilisateurs de ressources. De m\u00eame, une \u00e9valuation \u00e0 mi-parcours de l&rsquo;Autorit\u00e9 nationale de gestion de la s\u00e9cheresse a observ\u00e9 qu&rsquo;en d\u00e9l\u00e9guant les structures de gouvernance pour travailler en alignement avec les groupes locaux, les efforts nationaux de gestion de la s\u00e9cheresse avaient \u00e9t\u00e9 plus fructueux qu&rsquo;ils ne l&rsquo;avaient \u00e9t\u00e9 dans le cadre de l&rsquo;approche de gouvernance plus descendante adopt\u00e9e lors de la s\u00e9cheresse de 2009-2011.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des recherches suppl\u00e9mentaires sont n\u00e9cessaires pour comprendre dans quelle mesure une \u00e9volution vers un d\u00e9veloppement plus r\u00e9silient au climat pourrait avoir lieu au Kenya et, le cas \u00e9ch\u00e9ant, ce que d&rsquo;autres pays et communaut\u00e9s pourraient apprendre de cette r\u00e9ussite. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"how-clare-projects-are-strengthening-drought-resilience\"><strong>Comment les projets CLARE renforcent la r\u00e9sistance \u00e0 la s\u00e9cheresse<\/strong> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Plusieurs projets de recherche CLARE expliquent comment ils travaillent avec les communaut\u00e9s pour concevoir ensemble des solutions permettant de faire progresser l&rsquo;adaptation au climat et de renforcer la r\u00e9sistance \u00e0 la s\u00e9cheresse. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"bima-turning-drought-insurance-into-a-climate-adaptation-tool-in-kenya-s-asals\">BIMA : Faire de l&rsquo;assurance contre la s\u00e9cheresse un outil d&rsquo;adaptation au climat dans les ASAL du Kenya <\/h4>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"949\" height=\"351\" src=\"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/BIMA.jpg\" alt=\"\" class=\"wp-image-169564\" srcset=\"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/BIMA.jpg 949w, https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/BIMA-300x111.jpg 300w, https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/BIMA-768x284.jpg 768w\" sizes=\"(max-width: 949px) 100vw, 949px\" \/><figcaption class=\"wp-element-caption\">Utilisation de capteurs proximaux (Apogee MS-100) pour mesurer la qualit\u00e9 de la v\u00e9g\u00e9tation<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le comt\u00e9 de Tana River au Kenya, les communaut\u00e9s pastorales sont en premi\u00e8re ligne du changement climatique, aux prises avec des s\u00e9cheresses r\u00e9currentes, la d\u00e9gradation des sols et les pertes de b\u00e9tail qui sapent les moyens de subsistance et provoquent des conflits bas\u00e9s sur les ressources. <strong>Le <\/strong><a href=\"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/bima-2-2\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>projet BIMA <\/strong><\/a><strong>vise \u00e0 relever ces d\u00e9fis croissants gr\u00e2ce \u00e0 une approche innovante et communautaire de la r\u00e9silience \u00e0 la s\u00e9cheresse, ancr\u00e9e dans un mod\u00e8le am\u00e9lior\u00e9 d&rsquo;assurance b\u00e9tail bas\u00e9e sur un indice (IBLI) qui int\u00e8gre des donn\u00e9es satellitaires avanc\u00e9es et des syst\u00e8mes de connaissances locaux.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;aide d&rsquo;un syst\u00e8me de d\u00e9clenchement hybride &#8211; int\u00e9grant l&rsquo;imagerie satellite, les donn\u00e9es pluviom\u00e9triques de CHIRPS, dix stations m\u00e9t\u00e9orologiques locales et 108 sous-placettes de surveillance du fourrage &#8211; la BIMA cherche \u00e0 am\u00e9liorer de mani\u00e8re significative la pr\u00e9cision et l&rsquo;\u00e9quit\u00e9 des paiements d&rsquo;assurance. Cette initiative contribuera \u00e0 r\u00e9duire le risque de base et \u00e0 faire en sorte que les paiements refl\u00e8tent plus pr\u00e9cis\u00e9ment les conditions de s\u00e9cheresse locales et parviennent aux m\u00e9nages touch\u00e9s avant que les pertes de troupeaux ne deviennent irr\u00e9versibles.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La BIMA se distingue par l&rsquo;importance qu&rsquo;elle accorde \u00e0 l&rsquo;anticipation et \u00e0 l&rsquo;\u00e9quit\u00e9. Les signaux d&rsquo;alerte pr\u00e9coce seront transform\u00e9s en informations opportunes et exploitables via la plateforme 3Map IMS, compl\u00e9t\u00e9e par des indicateurs climatiques indig\u00e8nes fournis par des experts en connaissances locales et des \u00e9claireurs communautaires form\u00e9s. En outre, la conception de la BIMA donne la priorit\u00e9 \u00e0 l&rsquo;inclusion des femmes, en veillant \u00e0 ce que les femmes, qui jouent un r\u00f4le essentiel dans la gestion des actifs des m\u00e9nages, b\u00e9n\u00e9ficient \u00e9galement des solutions d&rsquo;assurance.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parall\u00e8lement \u00e0 la protection financi\u00e8re, la BIMA encourage la gestion durable des p\u00e2turages en liant les paiements \u00e0 des pratiques approuv\u00e9es par la communaut\u00e9 qui pr\u00e9servent les \u00e9cosyst\u00e8mes et minimisent la n\u00e9cessit\u00e9 de vendre du b\u00e9tail en d\u00e9tresse. Cette strat\u00e9gie permettra non seulement de renforcer la r\u00e9silience des m\u00e9nages, mais aussi de contribuer \u00e0 la restauration des terres et aux objectifs d&rsquo;adaptation au climat dans les r\u00e9gions arides et semi-arides du Kenya.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au fur et \u00e0 mesure de l&rsquo;\u00e9volution du projet, la BIMA fournira un mod\u00e8le \u00e9volutif de financement des risques climatiques qui associe la technologie, la participation locale et la gestion des \u00e9cosyst\u00e8mes. Cette approche s&rsquo;aligne sur les strat\u00e9gies de r\u00e9silience \u00e0 la s\u00e9cheresse du Kenya et de l&rsquo;IGAD, qui donnent la priorit\u00e9 \u00e0 l&rsquo;adaptation au climat, \u00e0 l&rsquo;\u00e9galit\u00e9 des sexes et \u00e0 l&rsquo;inclusion financi\u00e8re.  <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"clarity-dodoma-t-lab\">CLARITY: le T-Lab Dodoma <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/clareprogramme.org\/fr\/update\/getting-better-at-mapping-the-story-of-water-in-tropical-drylands\/clarity\/\" target=\"_blank\" rel=\"noreferrer noopener\">Le projet CLARITY <\/a>en Dodoma, Tanzanie, <strong>s&rsquo;attaque aux d\u00e9fis croissants de la d\u00e9sertification et de la s\u00e9cheresse par le biais d&rsquo;une approche inclusive, fond\u00e9e sur la science et bas\u00e9e sur la communaut\u00e9.<\/strong>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au c\u0153ur du projet se trouvent les laboratoires de transformation <strong>les laboratoires de transformation<\/strong> (T-Labs), qui servent d&rsquo;espaces d&rsquo;innovation collaborative o\u00f9 les parties prenantes locales, les scientifiques, les d\u00e9cideurs politiques et les membres des communaut\u00e9s cocr\u00e9ent des voies de d\u00e9veloppement \u00e9quitables et durables dans les zones arides qui sont r\u00e9silientes au changement climatique. Ces T-Labs soutiennent le d\u00e9veloppement de voies de transformation en int\u00e9grant la mod\u00e9lisation scientifique du climat, de l&rsquo;utilisation des terres et des syst\u00e8mes d&rsquo;eaux souterraines aux connaissances locales, am\u00e9liorant ainsi la compr\u00e9hension des syst\u00e8mes homme-eau et informant une prise de d\u00e9cision efficace.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet met particuli\u00e8rement l&rsquo;accent sur la recharge, l&rsquo;acc\u00e8s et la surveillance des eaux souterraines. En surveillant et en instrumentant le barrage de Hombolo, il augmente la capacit\u00e9 de collecte des eaux de pluie pour l&rsquo;irrigation et la production de b\u00e9tail. Parall\u00e8lement, la construction de puits peu profonds am\u00e9liore l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau pour les communaut\u00e9s marginalis\u00e9es, en particulier les femmes et les \u00e9leveurs. Les para-hydrologues &#8211; membres de la communaut\u00e9 form\u00e9s \u00e0 la surveillance de l&rsquo;eau &#8211; jouent un r\u00f4le cl\u00e9 dans la collecte des donn\u00e9es et la sensibilisation, en veillant \u00e0 ce que les voix locales influencent la gestion des ressources en eau.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dimension de genre est int\u00e9gr\u00e9e dans l&rsquo;ensemble du projet, reconnaissant que les comportements individuels et collectifs en mati\u00e8re d&rsquo;utilisation de l&rsquo;eau sont influenc\u00e9s par les r\u00f4les des hommes et des femmes et par l&rsquo;acc\u00e8s aux ressources. Gr\u00e2ce \u00e0 des formations cibl\u00e9es et \u00e0 des opportunit\u00e9s de leadership, les femmes sont habilit\u00e9es \u00e0 participer \u00e0 la gouvernance de l&rsquo;eau et \u00e0 la restauration des terres. Le projet encourage \u00e9galement les pratiques de gestion durable des terres, y compris la protection des bassins versants, afin d&rsquo;am\u00e9liorer la recharge des nappes phr\u00e9atiques et de lutter contre la d\u00e9gradation des terres. La surveillance continue des eaux souterraines soutient la gestion adaptative et garantit que l&rsquo;utilisation de l&rsquo;eau reste dans des limites durables.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En associant des outils scientifiques \u00e0 une gouvernance participative, le projet renforce la r\u00e9silience non seulement des \u00e9cosyst\u00e8mes, mais aussi du tissu social des communaut\u00e9s des zones arides, offrant ainsi un mod\u00e8le reproductible d&rsquo;adaptation au climat qui renforce \u00e0 la fois la durabilit\u00e9 environnementale et le bien-\u00eatre humain face au stress climatique croissant. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"grin\">GRIN <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/clareprogramme.org\/grin\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>GRIN<\/strong><\/a><strong> contribue \u00e0 renforcer la r\u00e9silience \u00e0 la s\u00e9cheresse en travaillant avec plusieurs communaut\u00e9s de la r\u00e9gion de Savannah au Nigeria et au Ghana pour comprendre l&rsquo;exposition des m\u00e9nages et leur attitude face aux risques climatiques de s\u00e9cheresse et de mauvaises r\u00e9coltes, ainsi que la prise de d\u00e9cision au niveau de l&rsquo;exploitation et le potentiel d&rsquo;assurance des r\u00e9coltes.<\/strong> Au Ghana, le projet GRIN travaille dans trois communaut\u00e9s, Dua, Adaboje et Akansennga, dans le district de Bongo, dans la r\u00e9gion de l&rsquo;Upper East. Au Nigeria, l&rsquo;\u00e9tude a port\u00e9 sur deux zones de gouvernement local de l&rsquo;\u00c9tat de Kano &#8211; Tofa et Rimingado. Dans chacune de ces zones, trois communaut\u00e9s agricoles ont \u00e9t\u00e9 identifi\u00e9es : dans la zone de gouvernement local de Tofa, les communaut\u00e9s de Yansabo, Doka et Wangara, et dans la zone de gouvernement local de Rimingado, les communaut\u00e9s de Yalwandanziyal, Rimingado et Zango.   <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"palm-trees\">PALM-TREEs <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le project <\/strong><a href=\"https:\/\/clareprogramme.org\/fr\/update\/official-launch-of-the-palm-trees-project\/palm-trees\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>PALM-TREEs<\/strong><\/a><strong>a pour mission de relever les d\u00e9fis urgents de la s\u00e9cheresse et du stress thermique en Afrique subsaharienne, o\u00f9 les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames sont de plus en plus fr\u00e9quents.<\/strong> Selon le sixi\u00e8me rapport d&rsquo;\u00e9valuation du GIEC, ces \u00e9v\u00e9nements peuvent avoir des effets d\u00e9vastateurs, en particulier lorsque plusieurs risques se produisent simultan\u00e9ment. Dans le comt\u00e9 de Turkana, au Kenya, les communaut\u00e9s sont confront\u00e9es \u00e0 une grave p\u00e9nurie d&rsquo;eau et \u00e0 des effets \u00e0 long terme sur la sant\u00e9 mentale et le bien-\u00eatre. Au KwaZulu-Natal, en Afrique du Sud, l&rsquo;interaction du stress thermique et de la violence sexiste complique encore les vuln\u00e9rabilit\u00e9s auxquelles sont confront\u00e9es les populations locales. En Afrique centrale, les femmes des r\u00e9gions de Guider et de Foumbot, au Cameroun, subissent d&rsquo;importantes perturbations de la productivit\u00e9 agricole dues aux inondations et aux s\u00e9cheresses. Dans le bassin de la Volta au Ghana, le projet examine comment les extr\u00eames climatiques menacent la gestion de l&rsquo;eau et les pratiques agricoles, exacerbant les d\u00e9fis existants.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilisant une m\u00e9thodologie combinant les sciences physiques et sociales, le projet PALM-TREEs vise \u00e0 comprendre les impacts diff\u00e9rentiels de la s\u00e9cheresse et du stress thermique en fonction du genre et des identit\u00e9s sociales dans l&rsquo;ensemble de la r\u00e9gion. \u00c0 Lagos, au Nigeria, l&rsquo;accent est mis sur les probl\u00e8mes de sant\u00e9 et de moyens de subsistance auxquels sont confront\u00e9es les communaut\u00e9s vivant dans des zones d&rsquo;habitat informel en raison de la hausse des temp\u00e9ratures. De m\u00eame, en R\u00e9publique d\u00e9mocratique du Congo, le projet \u00e9value la mani\u00e8re dont les \u00e9v\u00e9nements climatiques extr\u00eames exacerbent les vuln\u00e9rabilit\u00e9s et perturbent la vie quotidienne. En utilisant des m\u00e9thodes de recherche qualitatives et quantitatives, telles que des entretiens et des \u00e9valuations de la vuln\u00e9rabilit\u00e9, ainsi que des mesures am\u00e9lior\u00e9es des al\u00e9as, le projet cherche \u00e0 d\u00e9velopper des strat\u00e9gies d&rsquo;adaptation sur mesure et des informations climatiques qui permettent aux communaut\u00e9s locales de se prendre en charge. Les r\u00e9sultats seront partag\u00e9s avec les d\u00e9cideurs politiques et les parties prenantes, favorisant ainsi une planification inclusive qui renforce la r\u00e9silience et s&rsquo;attaque aux in\u00e9galit\u00e9s. En fin de compte, le projet PALM-TREEs vise \u00e0 renforcer les capacit\u00e9s des communaut\u00e9s \u00e0 s&rsquo;adapter aux d\u00e9fis croissants pos\u00e9s par le climat actuel et futur dans divers contextes africains.      <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"passage\">PASSAGE <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/clareprogramme.org\/passage\" target=\"_blank\" rel=\"noreferrer noopener\">PASSAGE<\/a> vise \u00e0 renforcer la r\u00e9silience des communaut\u00e9s pastorales par le biais de r\u00e9cits de risques inclusifs et \u00e0 grande \u00e9chelle et de plans d&rsquo;action anticipatifs bas\u00e9s sur des pr\u00e9visions d&rsquo;impact multirisques. Le projet rassemble une \u00e9quipe diversifi\u00e9e de communaut\u00e9s pastorales, de gouvernements locaux et de la soci\u00e9t\u00e9 civile, qui s&rsquo;attaquent ensemble \u00e0 plusieurs lacunes en d\u00e9veloppant conjointement des r\u00e9cits de risques inclusifs et \u00e0 grande \u00e9chelle et des plans d&rsquo;action anticip\u00e9s (AA) bas\u00e9s sur des pr\u00e9visions d&rsquo;impacts multirisques.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet se concentre sp\u00e9cifiquement sur les zones transfrontali\u00e8res de la r\u00e9gion de l&rsquo;IGAD, car ces zones abritent les communaut\u00e9s pastorales et agro-pastorales les plus vuln\u00e9rables. Il est mis en \u0153uvre dans trois zones transfrontali\u00e8res de l&rsquo;IGAD, les groupes I, II et III, qui couvrent les zones transfrontali\u00e8res de l&rsquo;\u00c9thiopie, de la Somalie, du Sud-Soudan, de l&rsquo;Ouganda et du Kenya.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le travail de PASSAGE aborde les d\u00e9fis de la d\u00e9sertification et de la s\u00e9cheresse en mettant en place des mesures d&rsquo;att\u00e9nuation dans les domaines suivants :<\/strong>: <\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><strong>Mod\u00e9lisation et pr\u00e9vision des risques :<\/strong> Cartographie des eaux de surface \u00e0 court terme pour une analyse saisonni\u00e8re dans les trois groupes, collecte de donn\u00e9es sur les esp\u00e8ces v\u00e9g\u00e9tales envahissantes et les for\u00eats al\u00e9atoires pour g\u00e9n\u00e9rer des \u00e9chantillons de produits pour la cartographie, l&rsquo;utilisation des eaux souterraines et les pr\u00e9visions de la demande en \u00e9quipant des pompes de forage m\u00e9canis\u00e9es. <\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>L&rsquo;action anticip\u00e9e dans un contexte transfrontalier<\/strong>. <\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Communication des risques et engagement communautaire :<\/strong> Participation au groupe du secteur de l&rsquo;\u00e9levage dans les forums sur les perspectives climatiques de la Grande Corne de l&rsquo;Afrique (GHACOF) afin de promouvoir la production d&rsquo;avis fond\u00e9s sur des donn\u00e9es probantes concernant la surveillance des maladies, la production de fourrage, la disponibilit\u00e9 et l&rsquo;\u00e9tat des p\u00e2turages, les sch\u00e9mas de d\u00e9placement du b\u00e9tail, l&rsquo;infrastructure du commerce du b\u00e9tail, la collecte de l&rsquo;eau et la lutte contre les ravageurs. Ces avis sont transmis aux communaut\u00e9s, par l&rsquo;interm\u00e9diaire du sous-forum sur les perspectives climatiques, afin qu&rsquo;elles puissent prendre des d\u00e9cisions en connaissance de cause.  <\/li>\n<\/ol>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Renforcement des capacit\u00e9s :<\/strong> Soutien aux \u00e9tudiants en doctorat et en ma\u00eetrise dans le but de d\u00e9velopper des produits de connaissance sur les AA en vue de leur diffusion. <\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">D&rsquo;autres projets du portefeuille CLARE s&rsquo;attaquent \u00e9galement aux d\u00e9fis de la d\u00e9sertification et de la s\u00e9cheresse : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/clareprogramme.org\/basin\" target=\"_blank\" rel=\"noreferrer noopener\">BASIN<\/a> vise \u00e0 promouvoir la s\u00e9curit\u00e9 de l&rsquo;eau pour les communaut\u00e9s vuln\u00e9rables dans les pays africains, notamment en renfor\u00e7ant la r\u00e9sistance \u00e0 la s\u00e9cheresse, en examinant les comportements et les pratiques d&rsquo;adaptation afin d&rsquo;identifier des id\u00e9es et des actions pratiques qui r\u00e9pondent \u00e0 des pr\u00e9occupations intersectorielles et qui peuvent \u00eatre mises en \u0153uvre \u00e0 grande \u00e9chelle. D\u00e9couvrez comment BASIN<a href=\"https:\/\/clareprogramme.org\/update\/boosting-resilience-of-dryland-communities-through-sand-river-utilization-and-local-water-harvesting-innovations-in-central-tanzania\/\" title=\"\">renforce la r\u00e9silience des communaut\u00e9s des zones arides gr\u00e2ce \u00e0 l&rsquo;utilisation des rivi\u00e8res de sable et aux innovations locales en mati\u00e8re de collecte de l&rsquo;eau dans le centre de la Tanzanie.<\/a>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En Asie du Sud, <a href=\"https:\/\/clareprogramme.org\/success\" target=\"_blank\" rel=\"noreferrer noopener\">SUCCESS<\/a>\/CLAPS g\u00e9n\u00e8re de nouvelles connaissances sur l&rsquo;efficacit\u00e9 des adaptations qui impliquent de mani\u00e8re critique la migration, la mobilit\u00e9 et l&rsquo;immobilit\u00e9 comme strat\u00e9gie d&rsquo;adaptation aux s\u00e9cheresses et autres ph\u00e9nom\u00e8nes climatiques. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"looking-forward\">Regarder vers l&rsquo;avenir<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9silience au changement climatique et la r\u00e9silience \u00e0 la s\u00e9cheresse vont de pair. Comme le d\u00e9montrent les projets CLARE, des solutions d&rsquo;adaptation efficaces et inclusives, \u00e9labor\u00e9es en collaboration avec les communaut\u00e9s vuln\u00e9rables, peuvent fa\u00e7onner un avenir r\u00e9sistant \u00e0 la s\u00e9cheresse et au changement climatique.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"author":1,"featured_media":169567,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":""},"categories":[800],"tags":[],"clare_partners":[],"clare_projects":[729,722,806,1010,726,728,812],"clare_themes":[742,743,741],"clare_threads":[1357],"clare_topics":[623,602],"clare_countries":[],"clare_pillars":[794],"class_list":["post-169568","update","type-update","status-publish","has-post-thumbnail","hentry","category-blog-fr","clare_projects-adaptation-comportementale-securite-eau-inclusion-basin","clare_projects-construire-mecanismes-assurance-adaptation-bima","clare_projects-adaptation-aux-changements-climatiques-et-resilience-dans-les-zones-arides-tropicales-clarity","clare_projects-soutien-pour-la-preparation-au-risque-climatique-vers-une-assurance-recolte-tenant-compte-des-sexospecificites-en-afrique-de-louest-grin","clare_projects-regard-panafricain-transdisciplinaire-peripherie-afrique-faire-face-risques-evenements-extremes-palm-trees","clare_projects-renforcer-moyens-subsistance-eleveuses-eleveurs-grande-corne-afrique-mesures-anticipation-efficaces-passage","clare_projects-voies-intervention-reussies-migration-adaptation-success","clare_themes-action-precoce-basee-sur-le-risque","clare_themes-developpement-dans-un-climat-changeant","clare_themes-comprehension-du-risque-climatique","clare_threads-developpement-resilient-au-changement-climatique","clare_topics-eau","clare_topics-terres-arides-et-semi-arides","clare_pillars-recherche"],"blocksy_meta":[],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l&#039;\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l&#039;environnement, l&#039;\u00e9conomie et l&#039;aide humanitaire.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"CLARE Admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"Xgbg6vE8oVYVXn42teocL-IwTU90UzJVcVMZ6Y25JOc\" \/>\n\t<meta name=\"msvalidate.01\" content=\"036AC7A7063BA0CA3BB4B6DA1BD77167\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CLARE - CLimate Adaptation &amp; REsilience \u2013 Climate Adaptation &amp; Resilience\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation &amp; REsilience\" \/>\n\t\t<meta property=\"og:description\" content=\"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l&#039;\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l&#039;environnement, l&#039;\u00e9conomie et l&#039;aide humanitaire.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-16T20:36:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-01T13:24:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation &amp; REsilience\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l&#039;\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l&#039;environnement, l&#039;\u00e9conomie et l&#039;aide humanitaire.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/clare-updates\\\/#listItem\",\"name\":\"Mises \\u00e0 jour\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/clare-updates\\\/#listItem\",\"position\":2,\"name\":\"Mises \\u00e0 jour\",\"item\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/clare-updates\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/category\\\/blog-fr\\\/#listItem\",\"name\":\"Blogue\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/category\\\/blog-fr\\\/#listItem\",\"position\":3,\"name\":\"Blogue\",\"item\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/category\\\/blog-fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#listItem\",\"name\":\"L&rsquo;adaptation au climat et la r\\u00e9sistance \\u00e0 la s\\u00e9cheresse vont de pair\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/clare-updates\\\/#listItem\",\"name\":\"Mises \\u00e0 jour\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#listItem\",\"position\":4,\"name\":\"L&rsquo;adaptation au climat et la r\\u00e9sistance \\u00e0 la s\\u00e9cheresse vont de pair\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/category\\\/blog-fr\\\/#listItem\",\"name\":\"Blogue\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#organization\",\"name\":\"CLARE - CLimate Adaptation & REsilience\",\"description\":\"Climate Adaptation & Resilience\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/clare-logo_fr-landscape.png\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#organizationLogo\",\"width\":1440,\"height\":354,\"caption\":\"CLARE logo French\"},\"image\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/author\\\/clareadmin\\\/#author\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/author\\\/clareadmin\\\/\",\"name\":\"CLARE Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9282aa76e6fa7f3676c68297c24009d7422ffb6a7d4748fbe9aaddd46f7d3cc8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"CLARE Admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#webpage\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/\",\"name\":\"L\\u2019adaptation au climat et la r\\u00e9sistance \\u00e0 la s\\u00e9cheresse vont de pair | CLARE - CLimate Adaptation & REsilience\",\"description\":\"Les auteurs qui ont contribu\\u00e9 \\u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \\u00c0 l'\\u00e9chelle mondiale, le co\\u00fbt des s\\u00e9cheresses augmente, ce qui a des r\\u00e9percussions sur l'environnement, l'\\u00e9conomie et l'aide humanitaire.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/author\\\/clareadmin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/author\\\/clareadmin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ivan_kashinsky_106372-009_080_8717449477_o.jpg\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#mainImage\",\"width\":1920,\"height\":1280,\"caption\":\"Yolanda holds dead leaves from the branches of the avocado trees that she had to cut off to save the trees from the drought.  Yolanda Tapia Castillos, 77, lives in the drought stricken area of Quebrada Carcamo Norte, Chile.  She has lost many of her crops and has had to cut back all over her avocado trees.  \\rYolanda was interviewed.\\rPhotographer: Ivan Kashinsky:\\rivankphoto@gmail.com\\rivankphoto.com\\r+593 998127559\\r\\rPablo may be able to provide more information.  He was with me during the visits and has spent a great deal of time in the area. (I'm not sure if he speaks English) \\r\\rPablo Perry: pablo.perry@gmail.com\\r\\rOther contact:\\rDr.Fernando Santibanez Q.\\rCentro de Agricultura y Medio Ambiente\\rFacultad de Ciencias Agronomicas\\rUniversidad de Chile\\rCasilla 1004, Santiago, Chile\\rTel: 56-2-9785733\\\/34 Fax: 56-2-9785733\\rEmail:fsantiba@uchile.cl ; f_santibanez@yahoo.com\\rSkype: fersantib\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/update\\\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\\\/#mainImage\"},\"datePublished\":\"2025-06-16T16:36:24-04:00\",\"dateModified\":\"2025-08-01T09:24:48-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/\",\"name\":\"CLARE - CLimate Adaptation & REsilience\",\"description\":\"Climate Adaptation & Resilience\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/clareprogramme.org\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation & REsilience","description":"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l'\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l'environnement, l'\u00e9conomie et l'aide humanitaire.","canonical_url":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"Xgbg6vE8oVYVXn42teocL-IwTU90UzJVcVMZ6Y25JOc","msvalidate.01":"036AC7A7063BA0CA3BB4B6DA1BD77167","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/clareprogramme.org\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/clare-updates\/#listItem","name":"Mises \u00e0 jour"}},{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/clare-updates\/#listItem","position":2,"name":"Mises \u00e0 jour","item":"https:\/\/clareprogramme.org\/fr\/clare-updates\/","nextItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/#listItem","name":"Blogue"},"previousItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/#listItem","position":3,"name":"Blogue","item":"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#listItem","name":"L&rsquo;adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair"},"previousItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/clare-updates\/#listItem","name":"Mises \u00e0 jour"}},{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#listItem","position":4,"name":"L&rsquo;adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair","previousItem":{"@type":"ListItem","@id":"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/#listItem","name":"Blogue"}}]},{"@type":"Organization","@id":"https:\/\/clareprogramme.org\/fr\/#organization","name":"CLARE - CLimate Adaptation & REsilience","description":"Climate Adaptation & Resilience","url":"https:\/\/clareprogramme.org\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/clareprogramme.org\/wp-content\/uploads\/2023\/12\/clare-logo_fr-landscape.png","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#organizationLogo","width":1440,"height":354,"caption":"CLARE logo French"},"image":{"@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/clareprogramme.org\/fr\/author\/clareadmin\/#author","url":"https:\/\/clareprogramme.org\/fr\/author\/clareadmin\/","name":"CLARE Admin","image":{"@type":"ImageObject","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9282aa76e6fa7f3676c68297c24009d7422ffb6a7d4748fbe9aaddd46f7d3cc8?s=96&d=mm&r=g","width":96,"height":96,"caption":"CLARE Admin"}},{"@type":"WebPage","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#webpage","url":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/","name":"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation & REsilience","description":"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l'\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l'environnement, l'\u00e9conomie et l'aide humanitaire.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/clareprogramme.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#breadcrumblist"},"author":{"@id":"https:\/\/clareprogramme.org\/fr\/author\/clareadmin\/#author"},"creator":{"@id":"https:\/\/clareprogramme.org\/fr\/author\/clareadmin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg","@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#mainImage","width":1920,"height":1280,"caption":"Yolanda holds dead leaves from the branches of the avocado trees that she had to cut off to save the trees from the drought.  Yolanda Tapia Castillos, 77, lives in the drought stricken area of Quebrada Carcamo Norte, Chile.  She has lost many of her crops and has had to cut back all over her avocado trees.  \rYolanda was interviewed.\rPhotographer: Ivan Kashinsky:\rivankphoto@gmail.com\rivankphoto.com\r+593 998127559\r\rPablo may be able to provide more information.  He was with me during the visits and has spent a great deal of time in the area. (I'm not sure if he speaks English) \r\rPablo Perry: pablo.perry@gmail.com\r\rOther contact:\rDr.Fernando Santibanez Q.\rCentro de Agricultura y Medio Ambiente\rFacultad de Ciencias Agronomicas\rUniversidad de Chile\rCasilla 1004, Santiago, Chile\rTel: 56-2-9785733\/34 Fax: 56-2-9785733\rEmail:fsantiba@uchile.cl ; f_santibanez@yahoo.com\rSkype: fersantib"},"primaryImageOfPage":{"@id":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/#mainImage"},"datePublished":"2025-06-16T16:36:24-04:00","dateModified":"2025-08-01T09:24:48-04:00"},{"@type":"WebSite","@id":"https:\/\/clareprogramme.org\/fr\/#website","url":"https:\/\/clareprogramme.org\/fr\/","name":"CLARE - CLimate Adaptation & REsilience","description":"Climate Adaptation & Resilience","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/clareprogramme.org\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"CLARE - CLimate Adaptation &amp; REsilience \u2013 Climate Adaptation &amp; Resilience","og:type":"article","og:title":"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation &amp; REsilience","og:description":"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l'\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l'environnement, l'\u00e9conomie et l'aide humanitaire.","og:url":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/","og:image":"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg","og:image:secure_url":"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg","og:image:width":1920,"og:image:height":1280,"article:published_time":"2025-06-16T20:36:24+00:00","article:modified_time":"2025-08-01T13:24:48+00:00","twitter:card":"summary_large_image","twitter:title":"L\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair | CLARE - CLimate Adaptation &amp; REsilience","twitter:description":"Les auteurs qui ont contribu\u00e9 \u00e0 ce blog sont les suivants : Mme Edith Abilogo (PALM-TREEs), Dr. Chukwuemeka J. Diji (GRIN), Prof. Japhet Kashaigili (CLARITY), Dr. Dominic Kathiya (PASSAGE), Dr. Caroline King-Okumu, Dr. Nicholas Oguge (BIMA), \u00c0 l'\u00e9chelle mondiale, le co\u00fbt des s\u00e9cheresses augmente, ce qui a des r\u00e9percussions sur l'environnement, l'\u00e9conomie et l'aide humanitaire.","twitter:image":"https:\/\/clareprogramme.org\/wp-content\/uploads\/2025\/06\/ivan_kashinsky_106372-009_080_8717449477_o.jpg"},"aioseo_meta_data":{"post_id":"169568","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"created":"2025-06-16 20:34:38","updated":"2025-08-01 13:25:04","ai":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/clareprogramme.org\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/clareprogramme.org\/fr\/clare-updates\/\" title=\"Mises \u00e0 jour\">Mises \u00e0 jour<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/\" title=\"Blogue\">Blogue<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tL\u2019adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/clareprogramme.org\/fr\/"},{"label":"Mises \u00e0 jour","link":"https:\/\/clareprogramme.org\/fr\/clare-updates\/"},{"label":"Blogue","link":"https:\/\/clareprogramme.org\/fr\/category\/blog-fr\/"},{"label":"L&rsquo;adaptation au climat et la r\u00e9sistance \u00e0 la s\u00e9cheresse vont de pair","link":"https:\/\/clareprogramme.org\/fr\/update\/ladaptation-au-climat-et-la-resistance-a-la-secheresse-vont-de-pair\/"}],"_links":{"self":[{"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/update\/169568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/update"}],"about":[{"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/types\/update"}],"author":[{"embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/media\/169567"}],"wp:attachment":[{"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/media?parent=169568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/categories?post=169568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/tags?post=169568"},{"taxonomy":"clare_partners","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_partners?post=169568"},{"taxonomy":"clare_projects","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_projects?post=169568"},{"taxonomy":"clare_themes","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_themes?post=169568"},{"taxonomy":"clare_threads","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_threads?post=169568"},{"taxonomy":"clare_topics","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_topics?post=169568"},{"taxonomy":"clare_countries","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_countries?post=169568"},{"taxonomy":"clare_pillars","embeddable":true,"href":"https:\/\/clareprogramme.org\/fr\/wp-json\/wp\/v2\/clare_pillars?post=169568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}